{"id":623,"date":"2023-04-10T22:19:12","date_gmt":"2023-04-11T01:19:12","guid":{"rendered":"https:\/\/valedoaraguaianoticias.com.br\/site\/?page_id=623"},"modified":"2023-04-18T16:22:47","modified_gmt":"2023-04-18T19:22:47","slug":"policial","status":"publish","type":"page","link":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/","title":{"rendered":"POLICIAL"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"623\" class=\"elementor elementor-623\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-826d82e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"826d82e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cdb851\" data-id=\"3cdb851\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79093149 elementor-widget elementor-widget-heading\" data-id=\"79093149\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Policial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-285f5a8c elementor-section-content-middle elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"285f5a8c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f439b61\" data-id=\"3f439b61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cee857d elementor-widget elementor-widget-image\" data-id=\"cee857d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"250\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png\" class=\"attachment-full size-full wp-image-379\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ba4c8b7 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"5ba4c8b7\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4018724a\" data-id=\"4018724a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b9f43ba elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"5b9f43ba\" data-element_type=\"widget\" data-settings=\"{&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.86999999999999999555910790149937383830547332763671875,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-3958 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque category-policial\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/02\/21\/filho-de-ex-prefeito-e-assassinado-a-tiros-durante-assalto-em-fazenda-criminosos-fogem-com-carros-e-refens\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"1018\" height=\"737\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3959\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080.jpg 1018w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080-300x217.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080-768x556.jpg 768w\" sizes=\"(max-width: 1018px) 100vw, 1018px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFilho de ex-prefeito \u00e9 assassinado a tiros durante assalto em fazenda; criminosos fogem com carros e ref\u00e9ns\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-3950 post type-post status-publish format-standard has-post-thumbnail hentry category-cidades category-policial tag-seguranca-publica\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/02\/15\/prefeitura-de-lagoa-da-confusao-recebe-demandas-com-secretario-bruno-azevedo-com-o-objetivo-de-fortalece-dialogo-sobre-a-seguranca-publica-de-lagoa-da-confusao\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"670\" height=\"383\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/410852.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3951\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/410852.jpg 670w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/410852-300x171.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPrefeitura de Lagoa da Confus\u00e3o recebe demandas com Secret\u00e1rio Bruno Azevedo com o objetivo de fortalece di\u00e1logo sobre a seguran\u00e7a p\u00fablica de Lagoa da Confus\u00e3o\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-3577 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque category-policial tag-motorista-de-onibus-e-preso\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2024\/07\/11\/motorista-de-onibus-e-preso-na-rodoviaria-de-goiania-apos-ser-flagrado-em-cima-de-adolescente-durante-viagem-diz-policia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"554\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3578\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM.jpg 984w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM-300x169.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM-768x432.jpg 768w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMotorista de \u00f4nibus \u00e9 preso na rodovi\u00e1ria de Goi\u00e2nia ap\u00f3s ser flagrado &#8216;em cima&#8217; de adolescente durante viagem, diz pol\u00edcia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-2934 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-policial tag-bezerros-morrendo-de-fome\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/12\/15\/guarda-ambiental-encontra-bois-e-bezerros-morrendo-de-fome-em-fazenda\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"738\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2936\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro.jpg 984w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro-300x225.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro-768x576.jpg 768w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGuarda Ambiental encontra bois e bezerros morrendo de fome em fazenda\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-2724 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-policial tag-acidente-tragico-da-to-080\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/13\/cinco-pessoas-morreram-no-acidente-tragico-da-to-080-entre-palmas-e-paraiso-nesta-terca\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"392\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/IMG-20230912-WA1776-696x392-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2726\" alt=\"\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCinco pessoas morreram no acidente tr\u00e1gico da TO-080 entre Palmas e Para\u00edso, nesta ter\u00e7a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-2711 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-danilo-cavalcante tag-foragido tag-irma\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/11\/irma-de-brasileiro-fugitivo-nos-eua-e-detida-e-deve-ser-deportada-diz-policia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"400\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/Capturar.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2713\" alt=\"\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIrm\u00e3 de brasileiro fugitivo nos EUA \u00e9 detida e deve ser deportada, diz pol\u00edcia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-417d0dde elementor-section-content-middle elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"417d0dde\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f846a09\" data-id=\"f846a09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13e22bdb elementor-widget elementor-widget-image\" data-id=\"13e22bdb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"250\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-2.png\" class=\"attachment-full size-full wp-image-384\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-479b22ea elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"479b22ea\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5670ba6b\" data-id=\"5670ba6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-348b65e5 elementor-grid-1 elementor-posts--thumbnail-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"348b65e5\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2688 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-baleado tag-morre tag-sargento\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/08\/sargento-morre-baleado-no-interior-de-sp-horas-depois-de-carregar-bandeira-do-brasil-em-cerimonia\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"635\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/escudopmesp.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2690\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/08\/sargento-morre-baleado-no-interior-de-sp-horas-depois-de-carregar-bandeira-do-brasil-em-cerimonia\/\" >\n\t\t\t\tSargento morre baleado no interior de SP horas depois de carregar bandeira do Brasil em cerim\u00f4nia\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Eduardo Sabatini Junior e um colega foram acionados pela manh\u00e3 para a regi\u00e3o de Itaqueri da Serra atender uma ocorr\u00eancia<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2616 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-goias tag-luziania tag-presidio\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/06\/upr-feminina-de-luziania-fica-entre-as-15-melhores-unidades-prisionais-do-pais\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1033\" height=\"667\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/snapinsta.app-371925062-18233101504229244-2708448277126599548-n-1080.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2618\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/06\/upr-feminina-de-luziania-fica-entre-as-15-melhores-unidades-prisionais-do-pais\/\" >\n\t\t\t\tUPR Feminina de Luzi\u00e2nia fica entre as 15 melhores unidades prisionais do pa\u00eds\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Unidade Prisional Regional Feminina de Luzi\u00e2nia, no entorno do Distrito Federal, foi classificada entre as 15 melhores unidades penitenci\u00e1rias<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2592 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-falsificacao tag-moedas tag-policia-federal\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/05\/policia-federal-cumpre-mandados-em-operacao-que-investiga-producao-e-comercio-de-moedas-falsas\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1486\" height=\"677\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/policia-federal.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2594\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/05\/policia-federal-cumpre-mandados-em-operacao-que-investiga-producao-e-comercio-de-moedas-falsas\/\" >\n\t\t\t\tPol\u00edcia Federal cumpre mandados em opera\u00e7\u00e3o que investiga produ\u00e7\u00e3o e com\u00e9rcio de moedas falsas\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Pol\u00edcia Federal cumpriu 22 mandados de busca e apreens\u00e3o, na manh\u00e3 desta ter\u00e7a-feira (5), em v\u00e1rias cidades do pa\u00eds.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2584 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-monique-medeiros tag-presidio\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/acusada-da-morte-do-filho-monique-medeiros-e-transferida-de-presidio\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/MONIQUE-MEDEIROS.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2586\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/acusada-da-morte-do-filho-monique-medeiros-e-transferida-de-presidio\/\" >\n\t\t\t\tAcusada da morte do filho, Monique Medeiros \u00e9 transferida de pres\u00eddio\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A professora Monique Medeiros foi transferida do Instituto Penal Santo Expedito para a Penitenci\u00e1ria Talavera Bruce, no Complexo de Gericin\u00f3,<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2580 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-amazonas tag-desaparecido tag-norte-americano\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/policia-do-am-investiga-sumico-de-norte-americano-que-casou-com-brasileira-durante-reality-show\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"743\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/noivos.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2582\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/policia-do-am-investiga-sumico-de-norte-americano-que-casou-com-brasileira-durante-reality-show\/\" >\n\t\t\t\tPol\u00edcia do AM investiga sumi\u00e7o de norte-americano que casou com brasileira durante reality show\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Pol\u00edcia Civil do Amazonas investiga o desaparecimento do norte-americano Paul Staehle, casado com uma amazonense que conheceu durante o<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-633d660b elementor-widget elementor-widget-image\" data-id=\"633d660b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"250\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-5.png\" class=\"attachment-full size-full wp-image-597\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9a9a93 elementor-grid-1 elementor-posts--thumbnail-left load-more-align-justify elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"e9a9a93\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;load_more_on_click&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2569 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-agressao tag-antony tag-jogador\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/policia-de-sp-ouve-testemunhas-no-caso-da-ex-namorada-que-acusa-jogador-antony-de-ameaca-e-agressao\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"997\" height=\"1536\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/ANTONY.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2571\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/policia-de-sp-ouve-testemunhas-no-caso-da-ex-namorada-que-acusa-jogador-antony-de-ameaca-e-agressao\/\" >\n\t\t\t\tPol\u00edcia de SP ouve testemunhas no caso da ex-namorada que acusa jogador Antony de amea\u00e7a e agress\u00e3o\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Pol\u00edcia Civil de S\u00e3o Paulo informou nesta segunda-feira (4) que continua ouvindo as testemunhas do caso da ex-namorada que<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2534 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete-segundaria category-noticias-em-destaque category-policial tag-vaqueiro-ve-urubus-e-encontra-corpo-de-idoso\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/08\/21\/vaqueiro-ve-urubus-e-encontra-corpo-de-idoso-que-estava-desaparecido-ha-10-dias\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"1312\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/08\/bombeiros.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2535\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/08\/21\/vaqueiro-ve-urubus-e-encontra-corpo-de-idoso-que-estava-desaparecido-ha-10-dias\/\" >\n\t\t\t\tVaqueiro v\u00ea urubus e encontra corpo de idoso que estava desaparecido h\u00e1 10 dias\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de agosto de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Teodorico Galdino Moura foi encontrado morto na encosta de uma serra, zona rural de Colinas do Tocantins. Segundo parentes, idoso<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2488 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete-segundaria category-noticias-em-destaque category-policial tag-padrasto-e-preso\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/08\/08\/padrasto-e-preso-por-suspeita-de-cometer-estupro-contra-enteada-de-apenas-11-anos\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"1263\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/08\/thumbnail-preso-sitio-novo-02-divulgacao-pcto.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2489\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/08\/08\/padrasto-e-preso-por-suspeita-de-cometer-estupro-contra-enteada-de-apenas-11-anos\/\" >\n\t\t\t\tPadrasto \u00e9 preso por suspeita de cometer estupro contra enteada de apenas 11 anos\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 de agosto de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Crime aconteceu em S\u00edtio Novo e homem foi localizado em ponte na divisa da cidade com o Maranh\u00e3o. M\u00e3e percebeu<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2485 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete-segundaria category-noticias-em-destaque category-policial tag-homem-faz-disparos-em-via-publica\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/08\/08\/homem-faz-disparos-em-via-publica-e-tenta-fugir-da-policia-nadando-em-rio\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"608\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/08\/341175.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2486\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/08\/08\/homem-faz-disparos-em-via-publica-e-tenta-fugir-da-policia-nadando-em-rio\/\" >\n\t\t\t\tHomem faz disparos em via p\u00fablica e tenta fugir da pol\u00edcia nadando em rio\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 de agosto de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Caso foi registrado na orla de Porto Nacional, na regi\u00e3o central do estado. Militares chamaram um barqueiro e conseguiram capturar<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"31\" data-next-page=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/pages\/623\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#\" class=\"elementor-button-link elementor-button\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">VEJA MAIS<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"e-load-more-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65f0c976\" data-id=\"65f0c976\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c8e4730 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c8e4730\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-10bdd1e8\" data-id=\"10bdd1e8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-627509bd elementor-widget elementor-widget-heading\" data-id=\"627509bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mais populares <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d14a59c elementor-grid-1 elementor-posts--thumbnail-left elementor-posts--align-left elementor-widget__width-initial elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"1d14a59c\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4164 post type-post status-publish format-standard has-post-thumbnail hentry category-cidades category-manchete category-manchete-segundaria category-noticias-em-destaque\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/11\/25\/vereador-do-povo-fabiano-cardoso-comemora-seu-aniversario\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"450\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4166\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil.jpg 770w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil-300x175.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil-768x449.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/11\/25\/vereador-do-povo-fabiano-cardoso-comemora-seu-aniversario\/\" >\n\t\t\t\tVEREADOR DO POVO FABIANO CARDOSO COMEMORA SEU ANIVERS\u00c1RIO\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4129 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/08\/18\/vereador-fabiano-cardoso-faz-representacao-no-ministerio-pubico-para-que-prefeito-de-pugmil-realize-o-pagamento-dos-valores-proporcionais-de-ferias-e-13o-dos-servidores-exonerados\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3825\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26.jpg 960w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26-225x300.jpg 225w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26-768x1024.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/08\/18\/vereador-fabiano-cardoso-faz-representacao-no-ministerio-pubico-para-que-prefeito-de-pugmil-realize-o-pagamento-dos-valores-proporcionais-de-ferias-e-13o-dos-servidores-exonerados\/\" >\n\t\t\t\tVereador Fabiano Cardoso faz representa\u00e7\u00e3o no Minist\u00e9rio P\u00fabico para que Prefeito de Pugmil realize o pagamento dos proporcionais de F\u00e9rias e 13\u00ba dos servidores sobre pena de Bloqueio do FPM\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4126 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque tag-acidente\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/22\/acidente-entre-carreta-e-carro-deixa-seis-mortos-na-br-153-diz-prf\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05.jpeg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4127\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05.jpeg 1000w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05-300x169.jpeg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05-768x432.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/22\/acidente-entre-carreta-e-carro-deixa-seis-mortos-na-br-153-diz-prf\/\" >\n\t\t\t\tAcidente entre carreta e carro deixa seis mortos na BR-153, diz PRF\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4107 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque tag-prefeitura-de-lagoa-da-confusao\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/04\/prefeito-de-lagoa-da-confusao-thiago-lagoense-esteve-em-brasilia-participando-do-evento-prefeitos-do-futuro\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso.jpeg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4115\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso.jpeg 1024w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso-300x200.jpeg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso-768x512.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/04\/prefeito-de-lagoa-da-confusao-thiago-lagoense-esteve-em-brasilia-participando-do-evento-prefeitos-do-futuro\/\" >\n\t\t\t\tPrefeito de Lagoa da Confus\u00e3o Thiago Lagoense esteve em Bras\u00edlia participando do evento &#8220;Prefeitos do Futuro&#8221;.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4081 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque tag-dia-d-de-vacinacao-contra-hpv\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/06\/05\/secretaria-municipal-de-saude-de-lagoa-da-confusao-promove-programacao-especial-de-arraia-da-vacinacao\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao.jpeg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4082\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao.jpeg 1080w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao-240x300.jpeg 240w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao-819x1024.jpeg 819w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao-768x960.jpeg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/06\/05\/secretaria-municipal-de-saude-de-lagoa-da-confusao-promove-programacao-especial-de-arraia-da-vacinacao\/\" >\n\t\t\t\tSecretaria Municipal de Sa\u00fade de Lagoa da Confus\u00e3o promove programa\u00e7\u00e3o especial de Arrai\u00e1 da Vacina\u00e7\u00e3o\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-77c4a895 elementor-widget elementor-widget-image\" data-id=\"77c4a895\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"600\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-8.png\" class=\"attachment-full size-full wp-image-627\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f41d922 elementor-section-content-middle elementor-hidden-desktop elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"3f41d922\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24941145\" data-id=\"24941145\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1afaa0ae elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"1afaa0ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"300\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Engaje-seu-publico.png\" class=\"attachment-large size-large wp-image-562\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-596eddc9 elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"596eddc9\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d4ebc87\" data-id=\"3d4ebc87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70836526 elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"70836526\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3958 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque category-policial\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/02\/21\/filho-de-ex-prefeito-e-assassinado-a-tiros-durante-assalto-em-fazenda-criminosos-fogem-com-carros-e-refens\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1018\" height=\"737\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3959\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080.jpg 1018w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080-300x217.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/Snapinst.app_480941011_17868805653311986_2839910519731289669_n_1080-768x556.jpg 768w\" sizes=\"(max-width: 1018px) 100vw, 1018px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/02\/21\/filho-de-ex-prefeito-e-assassinado-a-tiros-durante-assalto-em-fazenda-criminosos-fogem-com-carros-e-refens\/\" >\n\t\t\t\tFilho de ex-prefeito \u00e9 assassinado a tiros durante assalto em fazenda; criminosos fogem com carros e ref\u00e9ns\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 de fevereiro de 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3950 post type-post status-publish format-standard has-post-thumbnail hentry category-cidades category-policial tag-seguranca-publica\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/02\/15\/prefeitura-de-lagoa-da-confusao-recebe-demandas-com-secretario-bruno-azevedo-com-o-objetivo-de-fortalece-dialogo-sobre-a-seguranca-publica-de-lagoa-da-confusao\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"670\" height=\"383\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/410852.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3951\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/410852.jpg 670w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/02\/410852-300x171.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/02\/15\/prefeitura-de-lagoa-da-confusao-recebe-demandas-com-secretario-bruno-azevedo-com-o-objetivo-de-fortalece-dialogo-sobre-a-seguranca-publica-de-lagoa-da-confusao\/\" >\n\t\t\t\tPrefeitura de Lagoa da Confus\u00e3o recebe demandas com Secret\u00e1rio Bruno Azevedo com o objetivo de fortalece di\u00e1logo sobre a seguran\u00e7a p\u00fablica de Lagoa da Confus\u00e3o\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t15 de fevereiro de 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3577 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque category-policial tag-motorista-de-onibus-e-preso\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2024\/07\/11\/motorista-de-onibus-e-preso-na-rodoviaria-de-goiania-apos-ser-flagrado-em-cima-de-adolescente-durante-viagem-diz-policia\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"554\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3578\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM.jpg 984w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM-300x169.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/07\/PM-768x432.jpg 768w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2024\/07\/11\/motorista-de-onibus-e-preso-na-rodoviaria-de-goiania-apos-ser-flagrado-em-cima-de-adolescente-durante-viagem-diz-policia\/\" >\n\t\t\t\tMotorista de \u00f4nibus \u00e9 preso na rodovi\u00e1ria de Goi\u00e2nia ap\u00f3s ser flagrado &#8216;em cima&#8217; de adolescente durante viagem, diz pol\u00edcia\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t11 de julho de 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-761f9078 elementor-section-content-middle elementor-hidden-desktop elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"761f9078\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37289fb4\" data-id=\"37289fb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-406e2361 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"406e2361\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"300\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Engaje-seu-publico.png\" class=\"attachment-large size-large wp-image-562\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34ef2961 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"34ef2961\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2e2e126\" data-id=\"2e2e126\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e0d77d elementor-grid-1 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"69e0d77d\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2934 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-policial tag-bezerros-morrendo-de-fome\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/12\/15\/guarda-ambiental-encontra-bois-e-bezerros-morrendo-de-fome-em-fazenda\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"738\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2936\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro.jpg 984w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro-300x225.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/12\/image-bezerro-768x576.jpg 768w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/12\/15\/guarda-ambiental-encontra-bois-e-bezerros-morrendo-de-fome-em-fazenda\/\" >\n\t\t\t\tGuarda Ambiental encontra bois e bezerros morrendo de fome em fazenda\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t15 de dezembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2724 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-policial tag-acidente-tragico-da-to-080\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/13\/cinco-pessoas-morreram-no-acidente-tragico-da-to-080-entre-palmas-e-paraiso-nesta-terca\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"392\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/IMG-20230912-WA1776-696x392-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2726\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/13\/cinco-pessoas-morreram-no-acidente-tragico-da-to-080-entre-palmas-e-paraiso-nesta-terca\/\" >\n\t\t\t\tCinco pessoas morreram no acidente tr\u00e1gico da TO-080 entre Palmas e Para\u00edso, nesta ter\u00e7a\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2711 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-danilo-cavalcante tag-foragido tag-irma\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/11\/irma-de-brasileiro-fugitivo-nos-eua-e-detida-e-deve-ser-deportada-diz-policia\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"400\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/Capturar.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2713\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/11\/irma-de-brasileiro-fugitivo-nos-eua-e-detida-e-deve-ser-deportada-diz-policia\/\" >\n\t\t\t\tIrm\u00e3 de brasileiro fugitivo nos EUA \u00e9 detida e deve ser deportada, diz pol\u00edcia\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t11 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2688 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-baleado tag-morre tag-sargento\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/08\/sargento-morre-baleado-no-interior-de-sp-horas-depois-de-carregar-bandeira-do-brasil-em-cerimonia\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"635\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/escudopmesp.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2690\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/08\/sargento-morre-baleado-no-interior-de-sp-horas-depois-de-carregar-bandeira-do-brasil-em-cerimonia\/\" >\n\t\t\t\tSargento morre baleado no interior de SP horas depois de carregar bandeira do Brasil em cerim\u00f4nia\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t8 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61ed9aee elementor-widget elementor-widget-image\" data-id=\"61ed9aee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"300\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Engaje-seu-publico.png\" class=\"attachment-large size-large wp-image-562\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc81d99 elementor-grid-1 load-more-align-justify elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"fc81d99\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;load_more_on_click&quot;,&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2616 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-goias tag-luziania tag-presidio\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/06\/upr-feminina-de-luziania-fica-entre-as-15-melhores-unidades-prisionais-do-pais\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1033\" height=\"667\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/snapinsta.app-371925062-18233101504229244-2708448277126599548-n-1080.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2618\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/06\/upr-feminina-de-luziania-fica-entre-as-15-melhores-unidades-prisionais-do-pais\/\" >\n\t\t\t\tUPR Feminina de Luzi\u00e2nia fica entre as 15 melhores unidades prisionais do pa\u00eds\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t6 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2592 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-falsificacao tag-moedas tag-policia-federal\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/05\/policia-federal-cumpre-mandados-em-operacao-que-investiga-producao-e-comercio-de-moedas-falsas\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1486\" height=\"677\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/policia-federal.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2594\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/05\/policia-federal-cumpre-mandados-em-operacao-que-investiga-producao-e-comercio-de-moedas-falsas\/\" >\n\t\t\t\tPol\u00edcia Federal cumpre mandados em opera\u00e7\u00e3o que investiga produ\u00e7\u00e3o e com\u00e9rcio de moedas falsas\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t5 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2584 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-monique-medeiros tag-presidio\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/acusada-da-morte-do-filho-monique-medeiros-e-transferida-de-presidio\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"700\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/MONIQUE-MEDEIROS.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2586\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/acusada-da-morte-do-filho-monique-medeiros-e-transferida-de-presidio\/\" >\n\t\t\t\tAcusada da morte do filho, Monique Medeiros \u00e9 transferida de pres\u00eddio\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2580 post type-post status-publish format-standard has-post-thumbnail hentry category-policial tag-amazonas tag-desaparecido tag-norte-americano\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/policia-do-am-investiga-sumico-de-norte-americano-que-casou-com-brasileira-durante-reality-show\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"743\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/09\/noivos.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-2582\" alt=\"\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h4 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/09\/04\/policia-do-am-investiga-sumico-de-norte-americano-que-casou-com-brasileira-durante-reality-show\/\" >\n\t\t\t\tPol\u00edcia do AM investiga sumi\u00e7o de norte-americano que casou com brasileira durante reality show\t\t\t<\/a>\n\t\t<\/h4>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t4 de setembro de 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"32\" data-next-page=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/pages\/623\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"#\" class=\"elementor-button-link elementor-button\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">VEJA MAIS <\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"e-load-more-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da0bc23 elementor-widget elementor-widget-image\" data-id=\"1da0bc23\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"600\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-8.png\" class=\"attachment-large size-large wp-image-627\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a9fa64\" data-id=\"6a9fa64\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27a37796 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27a37796\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3e2f3474\" data-id=\"3e2f3474\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36a2a3c4 elementor-widget elementor-widget-heading\" data-id=\"36a2a3c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mais populares <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e232ad elementor-grid-1 elementor-posts--thumbnail-left elementor-posts--align-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"26e232ad\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4164 post type-post status-publish format-standard has-post-thumbnail hentry category-cidades category-manchete category-manchete-segundaria category-noticias-em-destaque\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/11\/25\/vereador-do-povo-fabiano-cardoso-comemora-seu-aniversario\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"450\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4166\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil.jpg 770w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil-300x175.jpg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/11\/Pugmil-768x449.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/11\/25\/vereador-do-povo-fabiano-cardoso-comemora-seu-aniversario\/\" >\n\t\t\t\tVEREADOR DO POVO FABIANO CARDOSO COMEMORA SEU ANIVERS\u00c1RIO\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4129 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/08\/18\/vereador-fabiano-cardoso-faz-representacao-no-ministerio-pubico-para-que-prefeito-de-pugmil-realize-o-pagamento-dos-valores-proporcionais-de-ferias-e-13o-dos-servidores-exonerados\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-3825\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26.jpg 960w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26-225x300.jpg 225w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2024\/12\/PHOTO-2024-09-16-18-26-26-768x1024.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/08\/18\/vereador-fabiano-cardoso-faz-representacao-no-ministerio-pubico-para-que-prefeito-de-pugmil-realize-o-pagamento-dos-valores-proporcionais-de-ferias-e-13o-dos-servidores-exonerados\/\" >\n\t\t\t\tVereador Fabiano Cardoso faz representa\u00e7\u00e3o no Minist\u00e9rio P\u00fabico para que Prefeito de Pugmil realize o pagamento dos proporcionais de F\u00e9rias e 13\u00ba dos servidores sobre pena de Bloqueio do FPM\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4126 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque tag-acidente\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/22\/acidente-entre-carreta-e-carro-deixa-seis-mortos-na-br-153-diz-prf\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05.jpeg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4127\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05.jpeg 1000w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05-300x169.jpeg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/whatsapp-image-2025-07-21-at-17.53.05-768x432.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/22\/acidente-entre-carreta-e-carro-deixa-seis-mortos-na-br-153-diz-prf\/\" >\n\t\t\t\tAcidente entre carreta e carro deixa seis mortos na BR-153, diz PRF\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4107 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque tag-prefeitura-de-lagoa-da-confusao\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/04\/prefeito-de-lagoa-da-confusao-thiago-lagoense-esteve-em-brasilia-participando-do-evento-prefeitos-do-futuro\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso.jpeg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4115\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso.jpeg 1024w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso-300x200.jpeg 300w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/07\/Congresso-768x512.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/07\/04\/prefeito-de-lagoa-da-confusao-thiago-lagoense-esteve-em-brasilia-participando-do-evento-prefeitos-do-futuro\/\" >\n\t\t\t\tPrefeito de Lagoa da Confus\u00e3o Thiago Lagoense esteve em Bras\u00edlia participando do evento &#8220;Prefeitos do Futuro&#8221;.\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4081 post type-post status-publish format-standard has-post-thumbnail hentry category-manchete category-manchete-segundaria category-noticias-em-destaque tag-dia-d-de-vacinacao-contra-hpv\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/06\/05\/secretaria-municipal-de-saude-de-lagoa-da-confusao-promove-programacao-especial-de-arraia-da-vacinacao\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao.jpeg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-4082\" alt=\"\" srcset=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao.jpeg 1080w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao-240x300.jpeg 240w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao-819x1024.jpeg 819w, https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2025\/06\/\ud83e\ude7a-Dia-D-de-Vacinacao-768x960.jpeg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2025\/06\/05\/secretaria-municipal-de-saude-de-lagoa-da-confusao-promove-programacao-especial-de-arraia-da-vacinacao\/\" >\n\t\t\t\tSecretaria Municipal de Sa\u00fade de Lagoa da Confus\u00e3o promove programa\u00e7\u00e3o especial de Arrai\u00e1 da Vacina\u00e7\u00e3o\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Policial Mais populares Mais populares<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-623","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>POLICIAL - Portal de Not\u00edcias Vale do Araguaia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POLICIAL - Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"og:description\" content=\"Policial Mais populares Mais populares\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-18T19:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/\",\"name\":\"POLICIAL - Portal de Not\u00edcias Vale do Araguaia\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png\",\"datePublished\":\"2023-04-11T01:19:12+00:00\",\"dateModified\":\"2023-04-18T19:22:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#primaryimage\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png\",\"width\":1600,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"POLICIAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"description\":\"Portal de Not\u00edcias\",\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"width\":285,\"height\":123,\"caption\":\"Portal de Not\u00edcias Vale do Araguaia\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POLICIAL - Portal de Not\u00edcias Vale do Araguaia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/","og_locale":"pt_BR","og_type":"article","og_title":"POLICIAL - Portal de Not\u00edcias Vale do Araguaia","og_description":"Policial Mais populares Mais populares","og_url":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/","og_site_name":"Portal de Not\u00edcias Vale do Araguaia","article_modified_time":"2023-04-18T19:22:47+00:00","og_image":[{"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/","name":"POLICIAL - Portal de Not\u00edcias Vale do Araguaia","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#primaryimage"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png","datePublished":"2023-04-11T01:19:12+00:00","dateModified":"2023-04-18T19:22:47+00:00","breadcrumb":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#primaryimage","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/04\/Design-sem-nome-1.png","width":1600,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/policial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/valedoaraguaianoticias.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"POLICIAL"}]},{"@type":"WebSite","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","name":"Portal de Not\u00edcias Vale do Araguaia","description":"Portal de Not\u00edcias","publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization","name":"Portal de Not\u00edcias Vale do Araguaia","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","width":285,"height":123,"caption":"Portal de Not\u00edcias Vale do Araguaia"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/pages\/623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/comments?post=623"}],"version-history":[{"count":13,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/pages\/623\/revisions"}],"predecessor-version":[{"id":1489,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/pages\/623\/revisions\/1489"}],"wp:attachment":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media?parent=623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}