{"id":1806,"date":"2023-06-19T12:34:35","date_gmt":"2023-06-19T15:34:35","guid":{"rendered":"https:\/\/valedoaraguaianoticias.com.br\/site\/?p=1806"},"modified":"2023-06-19T12:34:37","modified_gmt":"2023-06-19T15:34:37","slug":"lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021","status":"publish","type":"post","link":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/","title":{"rendered":"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021"},"content":{"rendered":"\n<p>Em 10 anos, mortes em acidentes de tr\u00e2nsito causados pelo uso de bebidas alco\u00f3licas ca\u00edram no pa\u00eds, mas hospitaliza\u00e7\u00f5es aumentaram, segundo levantamento do Centro de Informa\u00e7\u00f5es sobre Sa\u00fade e \u00c1lcool (CISA). Lei Seca entrou em vigor h\u00e1 exatos 15 anos no pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"984\" height=\"738\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png\" alt=\"\" class=\"wp-image-1807\"\/><\/figure>\n\n\n\n<p>Lei Seca completou 15 anos no Brasil com toler\u00e2ncia zero para motoristas alcoolizados.<\/p>\n\n\n\n<p>As mortes em acidentes de tr\u00e2nsito causados pela&nbsp;<strong>mistura de \u00e1lcool e dire\u00e7\u00e3o<\/strong>&nbsp;ca\u00edram 32% no Brasil entre 2010 e 2021, mas o \u00edndice de interna\u00e7\u00f5es aumentou 34% no mesmo per\u00edodo. Os dados foram divulgados pelo Centro de Informa\u00e7\u00f5es sobre Sa\u00fade e \u00c1lcool (CISA) nesta segunda-feira (19), dia em que a chamada&nbsp;<strong>Lei Seca<\/strong>&nbsp;completa 15 anos em vigor no pa\u00eds.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Em 2010, o \u00edndice era de&nbsp;<strong>7 mortes e 27 interna\u00e7\u00f5es<\/strong>&nbsp;a cada 100 mil habitantes.<\/li>\n\n\n\n<li>J\u00e1 em 2021, foram&nbsp;<strong>36 hospitaliza\u00e7\u00f5es e 5 \u00f3bitos&nbsp;<\/strong>a cada 100 mil habitantes.<\/li>\n<\/ul>\n\n\n\n<p>A perigosa e proibida mistura de bebida alco\u00f3lica com dire\u00e7\u00e3o causou 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no Brasil em 2021, de acordo com as informa\u00e7\u00f5es mais recentes levantadas pela entidade com base nos dados do Datasus, do Minist\u00e9rio da Sa\u00fade.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Foram 75.983 hospitaliza\u00e7\u00f5es e 10.887 \u00f3bitos por essa causa em 2021.<\/li>\n\n\n\n<li>Pessoas do sexo masculino representam 85% das interna\u00e7\u00f5es e 89% das mortes.<\/li>\n\n\n\n<li>Em rela\u00e7\u00e3o \u00e0 faixa et\u00e1ria, a popula\u00e7\u00e3o entre 18 e 34 anos de idade \u00e9 a mais afetada.<\/li>\n<\/ul>\n\n\n\n<p>\ud83d\udeab \ud83c\udf7a A Lei Seca, que endureceu as regras para o consumo de \u00e1lcool por motoristas, foi sancionada no dia 19 de junho de 2008. O Brasil \u00e9 um dos poucos pa\u00edses do mundo a estabelecer toler\u00e2ncia zero para quem dirigir alcoolizado ou sob efeito de subst\u00e2ncias psicoativas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cTer uma legisla\u00e7\u00e3o que pro\u00edba \u00e1lcool e dire\u00e7\u00e3o \u00e9 uma das estrat\u00e9gias mais eficazes para diminuir acidentes de tr\u00e2nsito no mundo e o fato de que eles v\u00eam perdendo consideravelmente sua letalidade no Brasil \u00e9 muito positivo&#8221;, disse Arthur Guerra, psiquiatra e presidente do CISA.<\/p>\n<\/blockquote>\n\n\n\n<p>&#8220;Mas sabemos que a preven\u00e7\u00e3o \u00e9 ainda mais efetiva quando a fiscaliza\u00e7\u00e3o \u00e9 constante e resulta em san\u00e7\u00f5es r\u00e1pidas e severas, e quando h\u00e1 campanhas de educa\u00e7\u00e3o\u201d, afirmou Guerra.<\/p>\n\n\n\n<p>\ud83d\udcc8 Segundo a an\u00e1lise feita pela entidade, a tend\u00eancia de queda foi vista tanto nas mortes como nas interna\u00e7\u00f5es entre os ocupantes de ve\u00edculos e pedestres. No entanto, entre ciclistas e motociclistas, houve crescimento das interna\u00e7\u00f5es.<\/p>\n\n\n\n<p>\u201c<strong>Em pequenas quantidades, o \u00e1lcool j\u00e1 \u00e9 capaz de alterar os reflexos do condutor<\/strong>&nbsp;e, conforme a concentra\u00e7\u00e3o de \u00e1lcool no sangue se eleva, aumenta tamb\u00e9m o risco de envolvimento em acidentes de tr\u00e2nsito graves&#8221;, explicou Guerra.<\/p>\n\n\n\n<p>\u26a0\ufe0f Cerca de 5,4% dos brasileiros relataram dirigir ap\u00f3s beber e esse \u00edndice apresenta estabilidade no Brasil, de acordo com a CISA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cen\u00e1rio nos estados<\/h2>\n\n\n\n<p>Mais da metade (17) dos estados brasileiros registraram \u00edndices de mortalidade superiores \u00e0 taxa nacional de 2021.<\/p>\n\n\n\n<p>Tocantins foi o estado que apresentou a maior taxa de\u00a0<strong>mortalidade<\/strong>: 11,8 \u00f3bitos a cada 100 mil habitantes. J\u00e1 o Rio de Janeiro, o \u00edndice foi o menor do Brasil, com 1,6 mortes.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">\u00d3bitos por acidentes de tr\u00e2nsito relacionados ao uso de \u00e1lcool em 2021<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Taxa \u00e9 calculada a cada 100 mil habitantes<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"731\" height=\"589\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-23.png\" alt=\"\" class=\"wp-image-1809\"\/><\/figure>\n\n\n\n<p>Fonte: Cisa, com informa\u00e7\u00f5es do Datasus.<\/p>\n\n\n\n<p>Nas\u00a0<strong>hospitaliza\u00e7\u00f5es<\/strong>, Piau\u00ed est\u00e1 em primeiro lugar no ranking dos estados, com 85,2 interna\u00e7\u00f5es para cada 100 mil habitantes. O menor \u00edndice foi registrado no Amazonas, com 11,8 casos.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Interna\u00e7\u00f5es por acidentes de tr\u00e2nsito relacionados ao uso de \u00e1lcool em 2021<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Taxa \u00e9 calculada a cada 100 mil habitantes<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"756\" height=\"599\" src=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-22.png\" alt=\"\" class=\"wp-image-1808\"\/><\/figure>\n\n\n\n<p>Fonte: Cisa, com informa\u00e7\u00f5es do Datasus.<\/p>\n\n\n\n<p>Segundo Mariana Thibes, soci\u00f3loga e coordenadora do CISA, \u00e9\u00a0<strong>preciso que as autoridades locais tomem medidas para reverter o cen\u00e1rio<\/strong>, como\u00a0<strong>aumentar o n\u00famero e frequ\u00eancia das fiscaliza\u00e7\u00f5e<\/strong>s e\u00a0<strong>implantar campanhas educativas<\/strong>.<\/p>\n\n\n\n<p>\u201cA educa\u00e7\u00e3o da popula\u00e7\u00e3o tem um importante papel na seguran\u00e7a vi\u00e1ria e, em rela\u00e7\u00e3o \u00e0 fiscaliza\u00e7\u00e3o, sabemos que quando n\u00e3o h\u00e1 continuidade, o impacto na redu\u00e7\u00e3o de mortes vi\u00e1rias tende a diminuir, apesar da exist\u00eancia de leis&#8221;, disse Mariana.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mais sobre a Lei Seca<\/h2>\n\n\n\n<p>O Brasil tem uma das legisla\u00e7\u00f5es mais rigorosas do mundo sobre consumo de \u00e1lcool e dire\u00e7\u00e3o de ve\u00edculos automotores.&nbsp;<strong>Dirigir sob efeito de \u00e1lcool em qualquer quantidade \u00e9 considerado crime no pa\u00eds.<\/strong><\/p>\n\n\n\n<p>A Lei n\u00ba 11.705, de 19 de junho de 2008, conhecida como Lei Seca, foi aperfei\u00e7oada ao longo dos anos. Ela estabelece&nbsp;<strong>toler\u00e2ncia zero<\/strong>&nbsp;para a presen\u00e7a de \u00e1lcool no sangue de condutores e puni\u00e7\u00f5es que v\u00e3o de multas \u00e0 pris\u00e3o, como em casos de acidentes que resultem em homic\u00eddio culposo ou les\u00e3o corporal.<\/p>\n\n\n\n<p>Em 2013, o Jornal Nacional mostrou como a Lei Seca ficou mais rigorosa ap\u00f3s mudan\u00e7as feitas pelo Conselho Nacional de Tr\u00e2nsito (Contran):<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 10 anos, mortes em acidentes de tr\u00e2nsito causados pelo uso de bebidas alco\u00f3licas ca\u00edram no pa\u00eds, mas hospitaliza\u00e7\u00f5es aumentaram, segundo levantamento do Centro de Informa\u00e7\u00f5es sobre Sa\u00fade e \u00c1lcool (CISA). Lei Seca entrou em vigor h\u00e1 exatos 15 anos no pa\u00eds. Lei Seca completou 15 anos no Brasil com toler\u00e2ncia zero para motoristas alcoolizados. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11,20,9],"tags":[169,168],"class_list":["post-1806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil-mundo","category-entretenimento","category-manchete-segundaria","category-policial","tag-lei-seca-15-anos","tag-mistura-de-alcool-com-direcao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021 - Portal de Not\u00edcias Vale do Araguaia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021 - Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"og:description\" content=\"Em 10 anos, mortes em acidentes de tr\u00e2nsito causados pelo uso de bebidas alco\u00f3licas ca\u00edram no pa\u00eds, mas hospitaliza\u00e7\u00f5es aumentaram, segundo levantamento do Centro de Informa\u00e7\u00f5es sobre Sa\u00fade e \u00c1lcool (CISA). Lei Seca entrou em vigor h\u00e1 exatos 15 anos no pa\u00eds. Lei Seca completou 15 anos no Brasil com toler\u00e2ncia zero para motoristas alcoolizados. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-19T15:34:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-19T15:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"redacao2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"redacao2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\"},\"author\":{\"name\":\"redacao2\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043\"},\"headline\":\"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021\",\"datePublished\":\"2023-06-19T15:34:35+00:00\",\"dateModified\":\"2023-06-19T15:34:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\"},\"wordCount\":822,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png\",\"keywords\":[\"Lei Seca 15 anos\",\"Mistura de \u00e1lcool com dire\u00e7\u00e3o\"],\"articleSection\":[\"BRASIL \/ MUNDO\",\"ENTRETENIMENTO\",\"MANCHETE SEGUND\u00c1RIA\",\"POLICIAL\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\",\"name\":\"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021 - Portal de Not\u00edcias Vale do Araguaia\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png\",\"datePublished\":\"2023-06-19T15:34:35+00:00\",\"dateModified\":\"2023-06-19T15:34:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png\",\"width\":984,\"height\":738},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"description\":\"Portal de Not\u00edcias\",\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"width\":285,\"height\":123,\"caption\":\"Portal de Not\u00edcias Vale do Araguaia\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043\",\"name\":\"redacao2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g\",\"caption\":\"redacao2\"},\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/author\/redacao2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021 - Portal de Not\u00edcias Vale do Araguaia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/","og_locale":"pt_BR","og_type":"article","og_title":"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021 - Portal de Not\u00edcias Vale do Araguaia","og_description":"Em 10 anos, mortes em acidentes de tr\u00e2nsito causados pelo uso de bebidas alco\u00f3licas ca\u00edram no pa\u00eds, mas hospitaliza\u00e7\u00f5es aumentaram, segundo levantamento do Centro de Informa\u00e7\u00f5es sobre Sa\u00fade e \u00c1lcool (CISA). Lei Seca entrou em vigor h\u00e1 exatos 15 anos no pa\u00eds. Lei Seca completou 15 anos no Brasil com toler\u00e2ncia zero para motoristas alcoolizados. [&hellip;]","og_url":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/","og_site_name":"Portal de Not\u00edcias Vale do Araguaia","article_published_time":"2023-06-19T15:34:35+00:00","article_modified_time":"2023-06-19T15:34:37+00:00","og_image":[{"width":984,"height":738,"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png","type":"image\/png"}],"author":"redacao2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"redacao2","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#article","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/"},"author":{"name":"redacao2","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043"},"headline":"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021","datePublished":"2023-06-19T15:34:35+00:00","dateModified":"2023-06-19T15:34:37+00:00","mainEntityOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/"},"wordCount":822,"commentCount":0,"publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png","keywords":["Lei Seca 15 anos","Mistura de \u00e1lcool com dire\u00e7\u00e3o"],"articleSection":["BRASIL \/ MUNDO","ENTRETENIMENTO","MANCHETE SEGUND\u00c1RIA","POLICIAL"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/","name":"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021 - Portal de Not\u00edcias Vale do Araguaia","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png","datePublished":"2023-06-19T15:34:35+00:00","dateModified":"2023-06-19T15:34:37+00:00","breadcrumb":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#primaryimage","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/06\/image-21.png","width":984,"height":738},{"@type":"BreadcrumbList","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/06\/19\/lei-seca-15-anos-mistura-de-alcool-com-direcao-causa-87-internacoes-e-12-mortes-por-hora-no-pais-em-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/valedoaraguaianoticias.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Lei Seca 15 anos: mistura de \u00e1lcool com dire\u00e7\u00e3o causa 8,7 interna\u00e7\u00f5es e 1,2 mortes por hora no pa\u00eds em 2021"}]},{"@type":"WebSite","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","name":"Portal de Not\u00edcias Vale do Araguaia","description":"Portal de Not\u00edcias","publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization","name":"Portal de Not\u00edcias Vale do Araguaia","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","width":285,"height":123,"caption":"Portal de Not\u00edcias Vale do Araguaia"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043","name":"redacao2","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g","caption":"redacao2"},"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/author\/redacao2\/"}]}},"views":19,"_links":{"self":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/1806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/comments?post=1806"}],"version-history":[{"count":1,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/1806\/revisions"}],"predecessor-version":[{"id":1810,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/1806\/revisions\/1810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media\/1807"}],"wp:attachment":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media?parent=1806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/categories?post=1806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/tags?post=1806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}