{"id":2062,"date":"2023-07-04T10:17:08","date_gmt":"2023-07-04T13:17:08","guid":{"rendered":"https:\/\/valedoaraguaianoticias.com.br\/site\/?p=2062"},"modified":"2023-07-04T10:17:10","modified_gmt":"2023-07-04T13:17:10","slug":"energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso","status":"publish","type":"post","link":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/","title":{"rendered":"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso"},"content":{"rendered":"\n<p>A Energisa oferece a partir desta segunda-feira (3), uma nova oportunidade para os clientes quitarem d\u00e9bitos com condi\u00e7\u00f5es de pagamento diferenciadas. Ser\u00e1 poss\u00edvel efetuar o parcelamento da d\u00edvida em at\u00e9 24 vezes no boleto ou no cart\u00e3o de cr\u00e9dito. A iniciativa, com poucas semanas de dura\u00e7\u00e3o, vai at\u00e9 18 de agosto e \u00e9 v\u00e1lida para todos os clientes tocantinenses. Outra op\u00e7\u00e3o \u00e9 para quem quiser quitar o d\u00e9bito a vista, com descontos que podem chegar at\u00e9 50% para faturas em atraso por mais de 30 dias.<\/p>\n\n\n\n<p>\u201cA Energisa quer facilitar a vida dos clientes e est\u00e1 analisando a situa\u00e7\u00e3o de cada um para chegar na melhor negocia\u00e7\u00e3o poss\u00edvel. Nosso objetivo \u00e9 que, diante das condi\u00e7\u00f5es atrativas que estamos oferecendo, todos possam quitar suas d\u00edvidas. Acreditamos que estamos no caminho certo no sentido de ajudar os nossos clientes, porque a \u00faltima campanha de negocia\u00e7\u00e3o teve uma \u00f3tima aceita\u00e7\u00e3o e conseguimos realizar mais de 115 mil negocia\u00e7\u00f5es em todas as \u00e1reas de concess\u00e3o da Energisa\u201d, refor\u00e7ou o Diretor de Prote\u00e7\u00e3o de Receita do Grupo, Newton Santos.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_1125032_1125028\"><img decoding=\"async\" src=\"https:\/\/i0.wp.com\/surgiu.com.br\/wp-content\/uploads\/2023\/07\/thumbnail-desconto-energia.jpg?resize=1920%2C1440&amp;ssl=1\" alt=\"\" class=\"wp-image-1125032\"\/><figcaption class=\"wp-element-caption\">Comunica\u00e7\u00e3o \u2013 ETO<\/figcaption><\/figure>\n\n\n\n<p><strong>Como negociar<\/strong><\/p>\n\n\n\n<p>A negocia\u00e7\u00e3o de d\u00edvidas pode ser feita de forma totalmente digital, sem necessidade de deslocamento do cliente at\u00e9 uma ag\u00eancia. Quem estiver com uma ou mais faturas vencidas pode entrar em contato pelos canais de atendimento como o WhatsApp da Gisa em www.gisa.energisa.com.br, aplicativo Energisa On (dispon\u00edvel nas lojas virtuais) e o site energisa.com.br. \u00c9 necess\u00e1rio ter em m\u00e3os os documentos pessoais de identifica\u00e7\u00e3o (CPF e RG).<\/p>\n\n\n\n<p><strong>Canais digitais<\/strong><\/p>\n\n\n\n<p>Aplicativo Energisa On (dispon\u00edvel para iOS e Android)<\/p>\n\n\n\n<p>Gisa: https:\/\/gisa.energisa.com.br\/<\/p>\n\n\n\n<p>Site: www.energisa.com.br<\/p>\n\n\n\n<p>Call Center: https:\/\/www.energisa.com.br\/paginas\/canais-de-atendimento\/telefones.aspx<\/p>\n\n\n\n<p><strong>Sobre a Energisa<\/strong><\/p>\n\n\n\n<p>Com 118 anos de hist\u00f3ria, a Energisa \u00e9 um dos maiores grupos privados com capital nacional do setor el\u00e9trico brasileiro. Somos um ecossistema de produtos e servi\u00e7os voltado para protagonizar a transforma\u00e7\u00e3o energ\u00e9tica, conectando pessoas e empresas \u00e0 melhor solu\u00e7\u00e3o de energia e construindo um mundo mais sustent\u00e1vel.<\/p>\n\n\n\n<p>O portf\u00f3lio da empresa abrange 9 distribuidoras e 12 concess\u00f5es de transmiss\u00e3o, uma marca inovadora de solu\u00e7\u00f5es energ\u00e9ticas \u2013 a (re)energisa \u2013, com gera\u00e7\u00e3o distribu\u00edda por fonte renov\u00e1vel, comercializa\u00e7\u00e3o de energia no mercado livre e servi\u00e7os de valor agregado, al\u00e9m de uma central de servi\u00e7os compartilhados, uma empresa de contact center e a fintech Voltz, a primeira no segmento de empresas de servi\u00e7o p\u00fablico de energia.<\/p>\n\n\n\n<p>No Tocantins, a Energisa atua como Distribuidora de Energia e est\u00e1 presente em todos os 139 munic\u00edpios do Estado. Desde que assumiu a concess\u00e3o de energia el\u00e9trica, a concession\u00e1ria vem trilhando um caminho de investimentos e avan\u00e7os significativos. Com um impressionante montante de mais de 2,6 bilh\u00f5es de reais investidos, a concession\u00e1ria demonstra compromisso em levar servi\u00e7os el\u00e9tricos de qualidade para 657 mil clientes tocantinenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Energisa oferece a partir desta segunda-feira (3), uma nova oportunidade para os clientes quitarem d\u00e9bitos com condi\u00e7\u00f5es de pagamento diferenciadas. Ser\u00e1 poss\u00edvel efetuar o parcelamento da d\u00edvida em at\u00e9 24 vezes no boleto ou no cart\u00e3o de cr\u00e9dito. A iniciativa, com poucas semanas de dura\u00e7\u00e3o, vai at\u00e9 18 de agosto e \u00e9 v\u00e1lida para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,20],"tags":[228],"class_list":["post-2062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete","category-manchete-segundaria","tag-descontos-de-ate-50-em-contas-de-luz-em-atraso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso - Portal de Not\u00edcias Vale do Araguaia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso - Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"og:description\" content=\"A Energisa oferece a partir desta segunda-feira (3), uma nova oportunidade para os clientes quitarem d\u00e9bitos com condi\u00e7\u00f5es de pagamento diferenciadas. Ser\u00e1 poss\u00edvel efetuar o parcelamento da d\u00edvida em at\u00e9 24 vezes no boleto ou no cart\u00e3o de cr\u00e9dito. A iniciativa, com poucas semanas de dura\u00e7\u00e3o, vai at\u00e9 18 de agosto e \u00e9 v\u00e1lida para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-04T13:17:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T13:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png\" \/>\n\t<meta property=\"og:image:width\" content=\"812\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"redacao2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"redacao2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\"},\"author\":{\"name\":\"redacao2\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043\"},\"headline\":\"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso\",\"datePublished\":\"2023-07-04T13:17:08+00:00\",\"dateModified\":\"2023-07-04T13:17:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\"},\"wordCount\":522,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png\",\"keywords\":[\"descontos de at\u00e9 50% EM contas de luz em atraso\"],\"articleSection\":[\"MANCHETE\",\"MANCHETE SEGUND\u00c1RIA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\",\"name\":\"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso - Portal de Not\u00edcias Vale do Araguaia\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png\",\"datePublished\":\"2023-07-04T13:17:08+00:00\",\"dateModified\":\"2023-07-04T13:17:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png\",\"width\":812,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"description\":\"Portal de Not\u00edcias\",\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"width\":285,\"height\":123,\"caption\":\"Portal de Not\u00edcias Vale do Araguaia\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043\",\"name\":\"redacao2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g\",\"caption\":\"redacao2\"},\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/author\/redacao2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso - Portal de Not\u00edcias Vale do Araguaia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/","og_locale":"pt_BR","og_type":"article","og_title":"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso - Portal de Not\u00edcias Vale do Araguaia","og_description":"A Energisa oferece a partir desta segunda-feira (3), uma nova oportunidade para os clientes quitarem d\u00e9bitos com condi\u00e7\u00f5es de pagamento diferenciadas. Ser\u00e1 poss\u00edvel efetuar o parcelamento da d\u00edvida em at\u00e9 24 vezes no boleto ou no cart\u00e3o de cr\u00e9dito. A iniciativa, com poucas semanas de dura\u00e7\u00e3o, vai at\u00e9 18 de agosto e \u00e9 v\u00e1lida para [&hellip;]","og_url":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/","og_site_name":"Portal de Not\u00edcias Vale do Araguaia","article_published_time":"2023-07-04T13:17:08+00:00","article_modified_time":"2023-07-04T13:17:10+00:00","og_image":[{"width":812,"height":612,"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png","type":"image\/png"}],"author":"redacao2","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"redacao2","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#article","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/"},"author":{"name":"redacao2","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043"},"headline":"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso","datePublished":"2023-07-04T13:17:08+00:00","dateModified":"2023-07-04T13:17:10+00:00","mainEntityOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/"},"wordCount":522,"commentCount":0,"publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png","keywords":["descontos de at\u00e9 50% EM contas de luz em atraso"],"articleSection":["MANCHETE","MANCHETE SEGUND\u00c1RIA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/","name":"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso - Portal de Not\u00edcias Vale do Araguaia","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png","datePublished":"2023-07-04T13:17:08+00:00","dateModified":"2023-07-04T13:17:10+00:00","breadcrumb":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#primaryimage","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/imagem_2023-07-04_101656760.png","width":812,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/04\/energisa-oferece-descontos-de-ate-50-e-parcelamento-para-renegociacao-de-contas-de-luz-em-atraso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/valedoaraguaianoticias.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Energisa oferece descontos de at\u00e9 50% e parcelamento para renegocia\u00e7\u00e3o de contas de luz em atraso"}]},{"@type":"WebSite","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","name":"Portal de Not\u00edcias Vale do Araguaia","description":"Portal de Not\u00edcias","publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization","name":"Portal de Not\u00edcias Vale do Araguaia","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","width":285,"height":123,"caption":"Portal de Not\u00edcias Vale do Araguaia"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/77e8c80795e1405426cf312c55c88043","name":"redacao2","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb492f3dd53bda3eef83e76d92733c536b21b79cb139513910e255980babace5?s=96&d=mm&r=g","caption":"redacao2"},"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/author\/redacao2\/"}]}},"views":13,"_links":{"self":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/2062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/comments?post=2062"}],"version-history":[{"count":1,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/2062\/revisions"}],"predecessor-version":[{"id":2064,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/2062\/revisions\/2064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media\/2063"}],"wp:attachment":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media?parent=2062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/categories?post=2062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/tags?post=2062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}