{"id":2365,"date":"2023-07-25T14:31:05","date_gmt":"2023-07-25T17:31:05","guid":{"rendered":"https:\/\/valedoaraguaianoticias.com.br\/site\/?p=2365"},"modified":"2023-07-25T14:34:53","modified_gmt":"2023-07-25T17:34:53","slug":"andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias","status":"publish","type":"post","link":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/","title":{"rendered":"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil"},"content":{"rendered":"\n<p><strong>Supersal\u00e1rios<\/strong><\/p>\n\n\n\n<p>Liminar dever\u00e1 ser referendada pelo plen\u00e1rio do STF.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/img2.migalhas.com.br\/_MEDPROC_\/https__img.migalhas.com.br__SL__gf_base__SL__empresas__SL__MIGA__SL__imagens__SL__2023__SL__07__SL__23__SL__fcae3992-4ffc-427e-83b6-f9d594595590.jpg._PROC_CP65.jpg\" alt=\" (Imagem: Nelson Jr.\/SCO\/STF)\" title=\"Andr\u00e9 Mendon\u00e7a suspende supersal\u00e1rios pagos a magistrados de Goi\u00e1s. \"\/><\/figure>\n\n\n\n<p>Andr\u00e9 Mendon\u00e7a suspende supersal\u00e1rios pagos a magistrados de Goi\u00e1s.&nbsp;(Imagem: Nelson Jr.\/SCO\/STF).<\/p>\n\n\n\n<p>Ministro&nbsp;<strong>Andr\u00e9 Mendon\u00e7a<\/strong>, do STF, suspendeu, neste s\u00e1bado, 22, cinco leis do estado de Goi\u00e1s que permitem que os servidores p\u00fablicos estaduais recebam sal\u00e1rios acima do teto do funcionalismo p\u00fablico, previsto na Constitui\u00e7\u00e3o Federal de 1988.&nbsp;<\/p>\n\n\n\n<p>Atualmente, este teto \u00e9 o equivalente ao valor do sal\u00e1rio dos ministros do STF (R$ 41,6 mil). <strong>Recentes reportagens mostraram sal\u00e1rios pagos a ju\u00edzes superiores a R$ 175 mil.&nbsp; &nbsp;<\/strong><\/p>\n\n\n\n<p>A medida cautelar concedida por Andr\u00e9 Mendon\u00e7a suspendeu imediatamente os efeitos das normas estaduais questionadas na ADIn 7.402, proposta pelo PGR, Augusto Aras.&nbsp;<\/p>\n\n\n\n<p>A AGU tamb\u00e9m se manifestou favor\u00e1vel ao deferimento da medida cautelar.&nbsp;<\/p>\n\n\n\n<p>A liminar ser\u00e1 submetida a referendo do plen\u00e1rio do STF.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Verbas indenizat\u00f3rias<\/strong><\/p>\n\n\n\n<p>Os artigos questionados s\u00e3o de cinco leis estaduais que regulamentam as verbas indenizat\u00f3rias atribu\u00eddas tanto a comissionados, como a funcion\u00e1rios p\u00fablicos efetivos do governo do estado, do Poder Judici\u00e1rio estadual, do Tribunal de Contas do Estado de Goi\u00e1s e dos munic\u00edpios goianos, al\u00e9m de procuradores do Minist\u00e9rio P\u00fablico de Contas (arts. 92, \u00a7 2\u00ba, e 94, par\u00e1grafo \u00fanico, da lei 21.792\/23; a lei 21.831\/23; o art. 2\u00ba da lei 21.832\/23; a lei 21.833\/23; e o art. 2\u00ba da lei 21.761\/22).&nbsp;<\/p>\n\n\n\n<p>As referidas normas regulamentavam o recebimento das chamadas &#8220;verbas indenizat\u00f3rias&#8221;, que ultrapassam o limite fixado pelo teto do funcionalismo p\u00fablico. O ministro Mendon\u00e7a discordou do texto destas legisla\u00e7\u00f5es.&nbsp;<em>&#8220;Para que se tipifique um gasto como indenizat\u00f3rio, n\u00e3o basta que a norma assim o considere.&#8221;&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p>Andr\u00e9 Mendon\u00e7a ressaltou que a Constitui\u00e7\u00e3o Federal estabelece os valores m\u00e1ximo e m\u00ednimo que podem prevalecer em qualquer das entidades pol\u00edticas ou suas entidades administrativas, em qualquer quadrante do pa\u00eds.\u00a0<em>&#8220;Tais valores correspondem aos limites m\u00e1ximo (fixado pelo subs\u00eddio do ministro do Supremo Tribunal Federal) e m\u00ednimo (que \u00e9 estabelecido pelo padr\u00e3o pecuni\u00e1rio definido legalmente como sal\u00e1rio-m\u00ednimo para qualquer trabalhador).&#8221;<\/em><\/p>\n\n\n\n<p>O magistrado entende ainda que valor m\u00e1ximo da remunera\u00e7\u00e3o recebido pelos servidores p\u00fablicos da Uni\u00e3o, estados, Distrito Federal e munic\u00edpios deve ser respeitado.<\/p>\n\n\n\n<p><em>&#8220;A observ\u00e2ncia da norma de teto de retribui\u00e7\u00e3o representa verdadeira condi\u00e7\u00e3o de legitimidade para o pagamento das remunera\u00e7\u00f5es no servi\u00e7o p\u00fablico.&#8221;<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Processo: ADIn&nbsp;<a href=\"https:\/\/portal.stf.jus.br\/processos\/detalhe.asp?incidente=6668374\" target=\"_blank\" rel=\"noreferrer noopener\">7.402<\/a><\/li>\n<\/ul>\n\n\n\n<p>Leia a&nbsp;<a href=\"https:\/\/www.migalhas.com.br\/arquivos\/2023\/7\/D7000C8D934132_decisaoandremendonca.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">decis\u00e3o<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Supersal\u00e1rios Liminar dever\u00e1 ser referendada pelo plen\u00e1rio do STF. Andr\u00e9 Mendon\u00e7a suspende supersal\u00e1rios pagos a magistrados de Goi\u00e1s.&nbsp;(Imagem: Nelson Jr.\/SCO\/STF). Ministro&nbsp;Andr\u00e9 Mendon\u00e7a, do STF, suspendeu, neste s\u00e1bado, 22, cinco leis do estado de Goi\u00e1s que permitem que os servidores p\u00fablicos estaduais recebam sal\u00e1rios acima do teto do funcionalismo p\u00fablico, previsto na Constitui\u00e7\u00e3o Federal de 1988.&nbsp; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,19,20,1],"tags":[342],"class_list":["post-2365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil-mundo","category-manchete","category-manchete-segundaria","category-noticias-em-destaque","tag-supersalarios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil - Portal de Not\u00edcias Vale do Araguaia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil - Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"og:description\" content=\"Supersal\u00e1rios Liminar dever\u00e1 ser referendada pelo plen\u00e1rio do STF. Andr\u00e9 Mendon\u00e7a suspende supersal\u00e1rios pagos a magistrados de Goi\u00e1s.&nbsp;(Imagem: Nelson Jr.\/SCO\/STF). Ministro&nbsp;Andr\u00e9 Mendon\u00e7a, do STF, suspendeu, neste s\u00e1bado, 22, cinco leis do estado de Goi\u00e1s que permitem que os servidores p\u00fablicos estaduais recebam sal\u00e1rios acima do teto do funcionalismo p\u00fablico, previsto na Constitui\u00e7\u00e3o Federal de 1988.&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de Not\u00edcias Vale do Araguaia\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T17:31:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T17:34:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Vale do Araguaia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Vale do Araguaia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o Vale do Araguaia\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/78764a729a5e1c14237ed3644b8f44df\"},\"headline\":\"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil\",\"datePublished\":\"2023-07-25T17:31:05+00:00\",\"dateModified\":\"2023-07-25T17:34:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\"},\"wordCount\":442,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg\",\"keywords\":[\"Supersal\u00e1rios\"],\"articleSection\":[\"BRASIL \/ MUNDO\",\"MANCHETE\",\"MANCHETE SEGUND\u00c1RIA\",\"NOT\u00cdCIAS EM DESTAQUE\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\",\"name\":\"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil - Portal de Not\u00edcias Vale do Araguaia\",\"isPartOf\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg\",\"datePublished\":\"2023-07-25T17:31:05+00:00\",\"dateModified\":\"2023-07-25T17:34:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg\",\"width\":880,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#website\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"description\":\"Portal de Not\u00edcias\",\"publisher\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization\",\"name\":\"Portal de Not\u00edcias Vale do Araguaia\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"contentUrl\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png\",\"width\":285,\"height\":123,\"caption\":\"Portal de Not\u00edcias Vale do Araguaia\"},\"image\":{\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/78764a729a5e1c14237ed3644b8f44df\",\"name\":\"Reda\u00e7\u00e3o Vale do Araguaia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea06f2240030465c5662dd894f45e56f62c2c38c1a333a45b48a8d6dcc64d602?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea06f2240030465c5662dd894f45e56f62c2c38c1a333a45b48a8d6dcc64d602?s=96&d=mm&r=g\",\"caption\":\"Reda\u00e7\u00e3o Vale do Araguaia\"},\"url\":\"https:\/\/valedoaraguaianoticias.com.br\/site\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil - Portal de Not\u00edcias Vale do Araguaia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/","og_locale":"pt_BR","og_type":"article","og_title":"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil - Portal de Not\u00edcias Vale do Araguaia","og_description":"Supersal\u00e1rios Liminar dever\u00e1 ser referendada pelo plen\u00e1rio do STF. Andr\u00e9 Mendon\u00e7a suspende supersal\u00e1rios pagos a magistrados de Goi\u00e1s.&nbsp;(Imagem: Nelson Jr.\/SCO\/STF). Ministro&nbsp;Andr\u00e9 Mendon\u00e7a, do STF, suspendeu, neste s\u00e1bado, 22, cinco leis do estado de Goi\u00e1s que permitem que os servidores p\u00fablicos estaduais recebam sal\u00e1rios acima do teto do funcionalismo p\u00fablico, previsto na Constitui\u00e7\u00e3o Federal de 1988.&nbsp; [&hellip;]","og_url":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/","og_site_name":"Portal de Not\u00edcias Vale do Araguaia","article_published_time":"2023-07-25T17:31:05+00:00","article_modified_time":"2023-07-25T17:34:53+00:00","og_image":[{"width":880,"height":507,"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Vale do Araguaia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Vale do Araguaia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#article","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/"},"author":{"name":"Reda\u00e7\u00e3o Vale do Araguaia","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/78764a729a5e1c14237ed3644b8f44df"},"headline":"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil","datePublished":"2023-07-25T17:31:05+00:00","dateModified":"2023-07-25T17:34:53+00:00","mainEntityOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/"},"wordCount":442,"commentCount":0,"publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg","keywords":["Supersal\u00e1rios"],"articleSection":["BRASIL \/ MUNDO","MANCHETE","MANCHETE SEGUND\u00c1RIA","NOT\u00cdCIAS EM DESTAQUE"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/","name":"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil - Portal de Not\u00edcias Vale do Araguaia","isPartOf":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage"},"thumbnailUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg","datePublished":"2023-07-25T17:31:05+00:00","dateModified":"2023-07-25T17:34:53+00:00","breadcrumb":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#primaryimage","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/07\/https__img.migalhas.com_.br_.jpg","width":880,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/2023\/07\/25\/andre-mendonca-suspende-pagamento-acima-do-teto-a-magistrados-de-goias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/valedoaraguaianoticias.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Supremo suspende cinco leis que permitiam sal\u00e1rios acima do teto constitucional de R$ 41,6 mil"}]},{"@type":"WebSite","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#website","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","name":"Portal de Not\u00edcias Vale do Araguaia","description":"Portal de Not\u00edcias","publisher":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valedoaraguaianoticias.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#organization","name":"Portal de Not\u00edcias Vale do Araguaia","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","contentUrl":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-content\/uploads\/2023\/03\/123.6.png","width":285,"height":123,"caption":"Portal de Not\u00edcias Vale do Araguaia"},"image":{"@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/78764a729a5e1c14237ed3644b8f44df","name":"Reda\u00e7\u00e3o Vale do Araguaia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/valedoaraguaianoticias.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea06f2240030465c5662dd894f45e56f62c2c38c1a333a45b48a8d6dcc64d602?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea06f2240030465c5662dd894f45e56f62c2c38c1a333a45b48a8d6dcc64d602?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o Vale do Araguaia"},"url":"https:\/\/valedoaraguaianoticias.com.br\/site\/author\/redacao\/"}]}},"views":24,"_links":{"self":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":2,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/2365\/revisions"}],"predecessor-version":[{"id":2369,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/posts\/2365\/revisions\/2369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media\/2366"}],"wp:attachment":[{"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/media?parent=2365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/categories?post=2365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/valedoaraguaianoticias.com.br\/site\/wp-json\/wp\/v2\/tags?post=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}